{"id":899,"date":"2016-12-10T13:09:08","date_gmt":"2016-12-10T11:09:08","guid":{"rendered":"http:\/\/sy-sy.synology.me\/?p=899"},"modified":"2019-12-22T17:37:48","modified_gmt":"2019-12-22T16:37:48","slug":"hlinene-setkani-v-lattes","status":"publish","type":"post","link":"https:\/\/blog.sy-sy.cz\/index.php\/2016\/12\/10\/hlinene-setkani-v-lattes\/","title":{"rendered":"Hlin\u011bn\u00e9 setk\u00e1n\u00ed v&nbsp;Lattes"},"content":{"rendered":"<p>Leto\u0161n\u00ed mezin\u00e1rodn\u00ed interdisciplin\u00e1rn\u00ed setk\u00e1n\u00ed s&nbsp;tematem historick\u00fdch konstrukc\u00ed z&nbsp;nep\u00e1len\u00e9 hl\u00edny,\u00a0 kter\u00e9 se konalo v&nbsp;archeologick\u00e9m muzeu <a href=\"http:\/\/museearcheo.montpellier3m.fr\/\">Mus\u00e9e Henri Prades<\/a> v&nbsp;Lattes ji\u017en\u011b od Montpellier, bylo, jak napov\u00edd\u00e1 i&nbsp;jeho n\u00e1zev:\u00a0<em>Echanges transdisciplinaires sur les constructions en terre crue. 4.: Terre crue : constructions en torchis et autres techniques de garnissage et de finition<\/em>, v&nbsp;po\u0159ad\u00ed ji\u017e \u010dtvrt\u00e9. Konference, jej\u00edm\u017e tematem byla lepenice, mazanice, mazanina, hlin\u011bn\u00e9 om\u00edtky a&nbsp;dal\u0161\u00ed vyu\u017eit\u00ed hl\u00edny jako nenosn\u00e9 konstrukce, <span class=\"journalName\">nab\u00eddla opravdu bohat\u00fd a&nbsp;kvalitn\u00ed program a&nbsp;byla zcela v&nbsp;duchu t\u011bch p\u0159edch\u00e1zej\u00edc\u00edch m\u00edstem pro p\u0159ekon\u00e1n\u00ed mezioborov\u00fdch barier.<\/span><!--more--><\/p>\n<p><img data-recalc-dims=\"1\" height=\"377\" width=\"625\" decoding=\"async\" class=\"thumbnail\" src=\"https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2016\/12\/P1190954bisbis_redimensionner-1.jpg?resize=625%2C377&#038;ssl=1\" alt=\"\" \/><\/p>\n<p><em>Konference se z\u00fa\u010dastnilo na 70 odborn\u00edk\u016f z&nbsp;Francie, \u0160pan\u011blska, N\u011bmecka, It\u00e1lie a&nbsp;\u010cesk\u00e9 republiky.<\/em><\/p>\n<p>M\u011bli jsme mo\u017enost zde p\u0159edn\u00e9st hned dva (vy\u017e\u00e1dan\u00e9) p\u0159\u00edsp\u011bvky na tema nep\u00e1len\u00e9 hl\u00edny v&nbsp;na\u0161ich historick\u00fdch d\u0159ehohlin\u011bn\u00fdch konstrukc\u00edch a&nbsp;historick\u00fdch hlin\u011bn\u00fdch om\u00edtek<span class=\"journalName\">. Prozat\u00edm jsou k&nbsp;dispozici pouze v&nbsp;r\u00e1mci <a href=\"https:\/\/blog.sy-sy.cz\/wp-content\/uploads\/2016\/12\/Ech-4-2016-preactes_r-1.pdf#pagemode=bookmarks&amp;page=1\" target=\"_blank\" rel=\"noopener noreferrer\">sborn\u00edku anotac\u00ed<\/a>: <\/span><\/p>\n<ul>\n<li><a href=\"https:\/\/blog.sy-sy.cz\/wp-content\/uploads\/2016\/12\/Ech-4-2016-preactes_r-1.pdf#pagemode=bookmarks&amp;page=34\" target=\"_blank\" rel=\"noopener noreferrer\">Le torchis dans les constructions historiques des pays tch\u00e8ques<\/a><\/li>\n<li><a href=\"https:\/\/blog.sy-sy.cz\/wp-content\/uploads\/2016\/12\/Ech-4-2016-preactes_r-1.pdf#pagemode=bookmarks&amp;page=36\" target=\"_blank\" rel=\"noopener noreferrer\">Les enduits de terre des b\u00e2timents dans le contexte de la r\u00e9gion danubienne (R\u00e9publique tch\u00e8que)<\/a><\/li>\n<\/ul>\n<p><span class=\"journalName\">Ve sborn\u00edku najdete i&nbsp;anotaci posteru koleg\u016f Merty a&nbsp;Pe\u0161ky z&nbsp;Archaia o.p.s., kte\u0159\u00ed se cesty na v&nbsp;dob\u011b konference nep\u0159\u00edli\u0161 vl\u00eddn\u00fd jih Francie nemohli bohu\u017eel z\u00fa\u010dastnit, tak\u017ee jsme nakonec prezentovali i&nbsp;jejich poster v\u011bnovan\u00fd systematick\u00e9mu v\u00fdzkumu d\u0159ev\u011bhlin\u011bn\u00fdch konstruc\u00ed na p\u0159\u00edkladu Brna a&nbsp;vesnickc\u00fdch staveb:<br \/>\n<\/span><\/p>\n<ul>\n<li><a href=\"https:\/\/blog.sy-sy.cz\/wp-content\/uploads\/2016\/12\/Ech-4-2016-preactes_r-1.pdf#pagemode=bookmarks&amp;page=65\" target=\"_blank\" rel=\"noopener noreferrer\">Architecture m\u00e9di\u00e9vale en bois et terre en Moravie d\u2019apr\u00e8s les sources arch\u00e9ologiques (exemples de recherche de sauvetage arch\u00e9ologique syst\u00e9matique de la ville et du village)<\/a><br \/>\n\/ <a href=\"https:\/\/blog.sy-sy.cz\/wp-content\/uploads\/2019\/12\/poster-Brno-Archaia-Brno.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">poster<\/a><\/li>\n<\/ul>\n<p><img data-recalc-dims=\"1\" height=\"457\" width=\"624\" decoding=\"async\" class=\"thumbnail\" src=\"https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2016\/12\/P1320835_-kopie-1.jpg?resize=624%2C457&#038;ssl=1\" alt=\"\" \/><\/p>\n<p><em>\u0160tafetu <\/em>Echanges transdisciplinaires sur les constructions en terre cru<em>e by m\u011bla p\u0159evz\u00edt nov\u011b zalo\u017een\u00e1 s\u00ed\u0165<\/em> <a href=\"https:\/\/reseauterre.hypotheses.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Reseau Terre<\/a><em> (kontakt terre.reseau@gmail.com), jej\u00ed\u017e zalo\u017een\u00ed bylo na konferenci ozn\u00e1meno.<\/em><\/p>\n<p><img data-recalc-dims=\"1\" height=\"468\" width=\"624\" decoding=\"async\" class=\"thumbnail\" src=\"https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2016\/12\/P1320830-2.jpg?resize=624%2C468&#038;ssl=1\" alt=\"\" \/><\/p>\n<p><em>Restituce galorom\u00e1nsk\u00e9ho domu m\u011bsta Lattara v&nbsp;parku muzea.\u00a0 Jeho konstrukce je pops\u00e1na ve sborn\u00edku abstrakt\u016f na str.\u00a0<a href=\"https:\/\/blog.sy-sy.cz\/wp-content\/uploads\/2016\/12\/Ech-4-2016-preactes_r-1.pdf#pagemode=bookmarks&amp;page=60\" target=\"_blank\" rel=\"noopener noreferrer\">60<\/a>.\u00a0 P\u0159i&nbsp;stavb\u011b byly na rozd\u00edl od p\u016fvodn\u00edho domu z&nbsp;nep\u00e1len\u00fdch cihel pou\u017eity dal\u0161\u00ed historick\u00e9 hlin\u011bn\u00e9 konstrukce (dusan\u00e1 a&nbsp;vrstven\u00e1 hl\u00edna). Sou\u010d\u00e1st\u00ed archeologick\u00e9ho zkoum\u00e1n\u00ed jsou i&nbsp;z\u00e1m\u011brn\u00e9 demolice a&nbsp;pozorov\u00e1n\u00ed rozkladu&#8230;<\/em><\/p>\n<ul>\n<li>Sborn\u00edk anotac\u00ed z&nbsp;konference:<br \/>\n&#8211; <a href=\"https:\/\/blog.sy-sy.cz\/wp-content\/uploads\/2016\/12\/Ech-4-2016-preactes_r-1.pdf\">TERRE CRUE : CONSTRUCTIONS EN TORCHIS &#8211; preactes<\/a><\/li>\n<li>Sborn\u00edky z&nbsp;p\u0159edchoz\u00edch koferenc\u00ed<br \/>\n&#8211; C.-A. de Chazelles, A. Klein (dir.) &#8211; \u00c9changes transdisciplinaires sur les constructions en terre crue, 1. Terre model\u00e9e, d\u00e9coup\u00e9e ou coffr\u00e9e. Mat\u00e9riaux et modes de mise en \u0153uvre. Actes de la table-ronde de Montpellier, 17-18 novembre 2001. Montpellier: \u00c9ditions de l\u2019Esp\u00e9rou, \u00c9cole d\u2019architecture du Languedoc-Roussillon, 2003, 460 p.<\/p>\n<div data-canvas-width=\"288.90891327845685\">&#8211; H. Guillaud, C.-A. de Chazelles, A. Klein (dir.) &#8211; Les constructions en terre massive: pis\u00e9 et bauge. \u00c9changes transdisciplinaires sur les constructions en terre crue, 2. Actes de la table-ronde de Villefontaine, 28-29 mai 2005. Montpellier: \u00c9ditions de l\u2019Esp\u00e9rou, \u00c9cole d\u2019architecture du Languedoc-Roussillon, 2007, 328 p.<\/div>\n<div data-canvas-width=\"189.64413403176187\">&#8211; C.-A. de Chazelles, A. Klein et N. Pousthomis (dir.) &#8211; Les cultures constructives de la brique crue. \u00c9changes transdisciplinaires sur les constructions en terre crue, 3. Actes du colloque international Les cultures constructives de la brique crue, Toulouse, 16-17 mai 2008. Montpellier: \u00c9ditions de l\u2019Esp\u00e9rou, \u00c9cole d\u2019architecture du Languedoc-Roussillon, 2011, 501 p.<\/div>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Leto\u0161n\u00ed mezin\u00e1rodn\u00ed interdisciplin\u00e1rn\u00ed setk\u00e1n\u00ed s&nbsp;tematem historick\u00fdch konstrukc\u00ed z&nbsp;nep\u00e1len\u00e9 hl\u00edny,\u00a0 kter\u00e9 se konalo v&nbsp;archeologick\u00e9m muzeu Mus\u00e9e Henri Prades v&nbsp;Lattes ji\u017en\u011b od Montpellier, bylo, jak napov\u00edd\u00e1 i&nbsp;jeho n\u00e1zev:\u00a0Echanges transdisciplinaires sur les constructions [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1020,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false,"_members_access_role":[],"_members_access_error":""},"categories":[5,13,41,9],"tags":[58,18],"class_list":["post-899","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hlina","category-konference","category-omazavky","category-udalost","tag-echanges-transdisciplinaires","tag-hlina-3"],"jetpack_shortlink":"https:\/\/wp.me\/p91gAT-ev","jetpack-related-posts":[{"id":2320,"url":"https:\/\/blog.sy-sy.cz\/index.php\/2019\/02\/12\/dva-hlinene\/","url_meta":{"origin":899,"position":0},"title":"Dva hlin\u011bn\u00e9","author":"Zuzana Syrov\u00e1 An\u00fd\u017eov\u00e1","date":"12\/02\/2019","format":false,"excerpt":"V prosinci vy\u0161el sborn\u00edk ze \u010dtvrt\u00e9 mezin\u00e1rodn\u00ed interdisciplin\u00e1rn\u00ed konference \/ kulat\u00e9ho stolu \/ s tematem historick\u00fdch hlin\u011bn\u00fdch konstrukc\u00ed, kter\u00e1 se konala 23.-25.listopadu v Lattes ve Francii a jej\u00edm\u017e tematem byla lepenice, mazanice, mazanina, hlin\u011bn\u00e9 om\u00edtky a\u00a0dal\u0161\u00ed vyu\u017eit\u00ed hl\u00edny jako nenosn\u00e9 konstrukce: \u00ab\u00a0Construction en terre crue. Torchis, techniques de garnissage et\u2026","rel":"","context":"V \u201eHlin\u011bn\u00e1 architektura a konstrukce\u201c","block_context":{"text":"Hlin\u011bn\u00e1 architektura a konstrukce","link":"https:\/\/blog.sy-sy.cz\/index.php\/category\/hlina\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2015\/12\/P1060134-2-e1503579391951.jpg?fit=1038%2C779&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2015\/12\/P1060134-2-e1503579391951.jpg?fit=1038%2C779&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2015\/12\/P1060134-2-e1503579391951.jpg?fit=1038%2C779&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2015\/12\/P1060134-2-e1503579391951.jpg?fit=1038%2C779&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2868,"url":"https:\/\/blog.sy-sy.cz\/index.php\/2022\/09\/18\/2868\/","url_meta":{"origin":899,"position":1},"title":"Hlin\u011bn\u00ed akt\u00e9\u0159i","author":"Zuzana Syrov\u00e1 An\u00fd\u017eov\u00e1","date":"18\/09\/2022","format":false,"excerpt":"V z\u00e1\u0159\u00ed vych\u00e1z\u00ed sborn\u00edk z p\u00e1t\u00e9 mezin\u00e1rodn\u00ed interdisciplin\u00e1rn\u00ed konference \/ kulat\u00e9ho stolu \/ s tematem historick\u00fdch hlin\u011bn\u00fdch konstrukc\u00ed, kter\u00e1 se konala 23.-24. \u0159\u00edjna v Montpellieru ve Francii a jej\u00edm\u017e tematem byl historick\u00fd, sociologick\u00fd a ekonomick\u00fd kontext jejich vzniku: \u00c9. Leal, C.-A. de Chazelles, P. Devillers (dir.),\u00a0Architecture et construction en terre\u2026","rel":"","context":"V \u201eHlin\u011bn\u00e1 architektura a konstrukce\u201c","block_context":{"text":"Hlin\u011bn\u00e1 architektura a konstrukce","link":"https:\/\/blog.sy-sy.cz\/index.php\/category\/hlina\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2022\/09\/499-35-e1663494775984.jpg?fit=1038%2C585&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2022\/09\/499-35-e1663494775984.jpg?fit=1038%2C585&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2022\/09\/499-35-e1663494775984.jpg?fit=1038%2C585&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2022\/09\/499-35-e1663494775984.jpg?fit=1038%2C585&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2133,"url":"https:\/\/blog.sy-sy.cz\/index.php\/2018\/06\/12\/hlinene-konstrukce-v-is-pamatkove-pece\/","url_meta":{"origin":899,"position":2},"title":"Hlin\u011bn\u00e9 konstrukce v&nbsp;IS pam\u00e1tkov\u00e9 p\u00e9\u010de","author":"Zuzana Syrov\u00e1 An\u00fd\u017eov\u00e1","date":"12\/06\/2018","format":false,"excerpt":"Na str\u00e1nk\u00e1ch CRATerre byla publikov\u00e1na online verze sborn\u00edku z konference Terra 2016\u00a0Terra Lyon 2016: actes \/ proceedings \/ actos : version en ligne\/online version\/versi\u00f3n en l\u00ednea, v n\u011bm\u017e\u00a0 najdete i n\u00e1\u0161 p\u0159\u00edsp\u011bvek Constructions en terre dans le syst\u00e8me d\u2019information du patrimoine (PDF). \u00a0 JOFFROY, Thierry, GUILLAUD, Hubert, SADOZA\u00cf, Chamsia (dir.)\u2026","rel":"","context":"V \u201eHlin\u011bn\u00e1 architektura a konstrukce\u201c","block_context":{"text":"Hlin\u011bn\u00e1 architektura a konstrukce","link":"https:\/\/blog.sy-sy.cz\/index.php\/category\/hlina\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2018\/06\/Carmen_SHora_1922-e1528816417404.jpg?fit=1038%2C710&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2018\/06\/Carmen_SHora_1922-e1528816417404.jpg?fit=1038%2C710&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2018\/06\/Carmen_SHora_1922-e1528816417404.jpg?fit=1038%2C710&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2018\/06\/Carmen_SHora_1922-e1528816417404.jpg?fit=1038%2C710&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":1828,"url":"https:\/\/blog.sy-sy.cz\/index.php\/2017\/10\/11\/hlinene-sos\/","url_meta":{"origin":899,"position":3},"title":"Hlin\u011bn\u00e9 SOS","author":"Zuzana Syrov\u00e1 An\u00fd\u017eov\u00e1","date":"11\/10\/2017","format":false,"excerpt":"V z\u00e1\u0159\u00ed jsme byli zase jednou ve Valencii, z n\u00ed\u017e na sn\u00edmku v z\u00e1hlav\u00ed p\u0159\u00edsp\u011bvku vid\u00edte detail hradby z dusan\u00e9 hl\u00edny spolu se zasv\u011bcenou pr\u016fvodn\u00ed postkonferen\u010dn\u00ed technick\u00e9 exkurze Valentinou Cristini. Exkurzi pochopiteln\u011b p\u0159edch\u00e1zela konference, kterou uspo\u0159\u00e1dali tamn\u00ed hlin\u011bn\u00ed aktivist\u00e9 Camilla Mileto a Fernando Vegas na \u0161kole architektury jako v po\u0159ad\u00ed\u2026","rel":"","context":"V \u201eHlin\u011bn\u00e1 architektura a konstrukce\u201c","block_context":{"text":"Hlin\u011bn\u00e1 architektura a konstrukce","link":"https:\/\/blog.sy-sy.cz\/index.php\/category\/hlina\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2017\/10\/0007928-e1507725150676.jpg?fit=1038%2C695&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2017\/10\/0007928-e1507725150676.jpg?fit=1038%2C695&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2017\/10\/0007928-e1507725150676.jpg?fit=1038%2C695&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2017\/10\/0007928-e1507725150676.jpg?fit=1038%2C695&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":1462,"url":"https:\/\/blog.sy-sy.cz\/index.php\/2017\/06\/24\/hlinene-vystavy\/","url_meta":{"origin":899,"position":4},"title":"Hlin\u011bn\u00e9 v\u00fdstavy tu i&nbsp;onde","author":"Zuzana Syrov\u00e1 An\u00fd\u017eov\u00e1","date":"24\/06\/2017","format":false,"excerpt":"Do konce 13. srpna lze v \u010cesk\u00fdch Bud\u011bjovic\u00edch zhl\u00e9dnout v\u00fdstavu Martin Rauch \u2013 Formovat zemi \/Refined Earth. V t\u00e9to souvislosti stoj\u00ed mo\u017en\u00e1 za to p\u0159ipomenout, \u017ee Martin Rauch je i laure\u00e1tem ceny Terra award, kter\u00e1\u017eto mu za technick\u00e9 inovace byla ud\u011blena na konferenci Terra 2016 v Lyonu. O konferenci jsme\u2026","rel":"","context":"V \u201eHlin\u011bn\u00e1 architektura a konstrukce\u201c","block_context":{"text":"Hlin\u011bn\u00e1 architektura a konstrukce","link":"https:\/\/blog.sy-sy.cz\/index.php\/category\/hlina\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2017\/08\/P1300409-e1503654684447.jpg?fit=1038%2C779&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2017\/08\/P1300409-e1503654684447.jpg?fit=1038%2C779&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2017\/08\/P1300409-e1503654684447.jpg?fit=1038%2C779&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2017\/08\/P1300409-e1503654684447.jpg?fit=1038%2C779&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":1412,"url":"https:\/\/blog.sy-sy.cz\/index.php\/2017\/06\/06\/rakouske-okenko-ii\/","url_meta":{"origin":899,"position":5},"title":"Rakousk\u00e9 ok\u00e9nko II","author":"Zuzana Syrov\u00e1 An\u00fd\u017eov\u00e1","date":"06\/06\/2017","format":false,"excerpt":"V prvn\u00edm kv\u011btnov\u00e9m t\u00fddnu se uskute\u010dnila leto\u0161n\u00ed rakousk\u00e1 \u010d\u00e1st odborn\u00e9 exkurze projektu Down to Earth \/ Zp\u011bt na zemi \u2013 Hlin\u011bn\u00e9 stavby ve st\u0159edn\u00ed Evrop\u011b (spole\u010dn\u00e9 \u010deskorakousk\u00e9 aktivity Mobility, na n\u00ed\u017e spolupracuje N\u00e1rodn\u00ed pam\u00e1tkov\u00fd \u00fastav, Archaia o.p.s. a IVA \u2013 ICRA Institute for Comparative Research in Architecture). Byl to skute\u010dn\u011b\u2026","rel":"","context":"V \u201eDusan\u00e1 hl\u00edna\u201c","block_context":{"text":"Dusan\u00e1 hl\u00edna","link":"https:\/\/blog.sy-sy.cz\/index.php\/category\/hlina\/dusana-hlina\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2017\/08\/0005680-e1503159901438.jpg?fit=1038%2C695&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2017\/08\/0005680-e1503159901438.jpg?fit=1038%2C695&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2017\/08\/0005680-e1503159901438.jpg?fit=1038%2C695&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2017\/08\/0005680-e1503159901438.jpg?fit=1038%2C695&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blog.sy-sy.cz\/wp-content\/uploads\/2016\/12\/0003774-2-e1503580555772.jpg?fit=1038%2C695&ssl=1","_links":{"self":[{"href":"https:\/\/blog.sy-sy.cz\/index.php\/wp-json\/wp\/v2\/posts\/899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.sy-sy.cz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.sy-sy.cz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.sy-sy.cz\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.sy-sy.cz\/index.php\/wp-json\/wp\/v2\/comments?post=899"}],"version-history":[{"count":3,"href":"https:\/\/blog.sy-sy.cz\/index.php\/wp-json\/wp\/v2\/posts\/899\/revisions"}],"predecessor-version":[{"id":2488,"href":"https:\/\/blog.sy-sy.cz\/index.php\/wp-json\/wp\/v2\/posts\/899\/revisions\/2488"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.sy-sy.cz\/index.php\/wp-json\/wp\/v2\/media\/1020"}],"wp:attachment":[{"href":"https:\/\/blog.sy-sy.cz\/index.php\/wp-json\/wp\/v2\/media?parent=899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.sy-sy.cz\/index.php\/wp-json\/wp\/v2\/categories?post=899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.sy-sy.cz\/index.php\/wp-json\/wp\/v2\/tags?post=899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}